{"id":23107,"date":"2022-08-17T10:23:46","date_gmt":"2022-08-17T08:23:46","guid":{"rendered":"https:\/\/magnusvinum.ch\/?post_type=product&#038;p=23107"},"modified":"2025-02-28T19:25:48","modified_gmt":"2025-02-28T17:25:48","slug":"meursault-les-narvaux-aoc-copy-2","status":"publish","type":"product","link":"https:\/\/magnusvinum.ch\/de\/shop\/weissweine\/meursault-les-narvaux-aoc-copy-2\/","title":{"rendered":"Meursault &#8218;Les Narvaux&#8216;  AOC"},"content":{"rendered":"<p><strong>Degustationsnotiz:<\/strong> Typische Meursault-Aromen von Haselnuss, Mandel und weissen Blumen. Mit der Zeit kommen Butter und Honig zum Vorschein. Am Gaumen ist er vollmundig und reichhaltig, jedoch mit einer guten Grundspannung. Ein Wein, der das Potenzial hat, sich \u00fcber einen langen Zeitraum zu entwickeln. Die beste Zeit ist etwa 5-15 Jahre nach der Ernte. <strong>Passt gut zu:<\/strong>\u00a0Perfekt zu Hummer, Langustinen, Kalbfleisch oder Gefl\u00fcgel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Degustationsnotiz: Typische Meursault-Aromen von Haselnuss, Mandel und weissen Blumen. Mit der Zeit kommen Butter und Honig zum Vorschein. Am Gaumen ist er vollmundig und reichhaltig, jedoch mit einer guten Grundspannung. Ein Wein, der das Potenzial hat, sich \u00fcber einen langen Zeitraum zu entwickeln. Die beste Zeit ist etwa 5-15 Jahre nach der Ernte. Passt gut &#8230; <a href=\"https:\/\/magnusvinum.ch\/de\/shop\/weissweine\/meursault-les-narvaux-aoc-copy-2\/\" class=\"more-link\">Read More <span class=\"screen-reader-text\">about  Meursault &#8218;Les Narvaux&#8216;  AOC<\/span><\/a><\/p>\n","protected":false},"featured_media":22045,"template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"product_brand":[790],"product_cat":[126],"product_tag":[776],"class_list":["post-23107","product","type-product","status-publish","has-post-thumbnail","product_brand-pascal-clement","product_cat-weissweine","product_tag-2022-de","pa_appellation-meursault-de","pa_bottle-size-750ml-de","pa_grape-variety-chardonnay-de","pa_producer-pascal-clement-de","pa_region-cote-de-beaune-de","pa_vintage-2022-de","entry","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"wooqr_code":"","_links":{"self":[{"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/product\/23107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/media\/22045"}],"wp:attachment":[{"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/media?parent=23107"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/product_brand?post=23107"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/product_cat?post=23107"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/product_tag?post=23107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}