{"id":11220,"date":"2019-10-29T13:04:21","date_gmt":"2019-10-29T11:36:11","guid":{"rendered":"https:\/\/magnusvinum.ch\/shop\/unkategorisiert\/pommard-1er-cru-les-rugiens-aoc-jeroboam\/"},"modified":"2020-02-13T14:59:27","modified_gmt":"2020-02-13T12:59:27","slug":"pommard-1er-cru-les-rugiens-aoc-jeroboam","status":"publish","type":"product","link":"https:\/\/magnusvinum.ch\/de\/shop\/rotweine\/pommard-1er-cru-les-rugiens-aoc-jeroboam\/","title":{"rendered":"Pommard 1er Cru Les Rugiens AOC (JEROBOAM)"},"content":{"rendered":"<p><strong>Degustationsnotiz:<\/strong> Rugiens ist f\u00fcr viele der archetypische Weinberg von Pommard und wird derzeit in Betracht gezogen, zum Grand Cru-Status aufgewertet zu werden. Das Jahr 2017 ist wie aus dem Lehrbuch mit rauchigen roten und schwarzen Fr\u00fcchten, getrockneten Orangenschalen, feinen Gew\u00fcrzen und Erde. Der Gaumen ist enorm konzentriert und mehrdimensional. Samtige und strukturierte Tannine schmeicheln dem Gaumen und f\u00fchren zu einem langen, kr\u00e4ftigen Abgang. Trinken Sie 2025-2050. <strong>Passt gut zu:<\/strong> Ein so besonderer Wein verdient ein besonderes Gericht. Gansbraten oder C\u00f4te de boeuf w\u00e4re gut!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Degustationsnotiz: Rugiens ist f\u00fcr viele der archetypische Weinberg von Pommard und wird derzeit in Betracht gezogen, zum Grand Cru-Status aufgewertet zu werden. Das Jahr 2017 ist wie aus dem Lehrbuch mit rauchigen roten und schwarzen Fr\u00fcchten, getrockneten Orangenschalen, feinen Gew\u00fcrzen und Erde. Der Gaumen ist enorm konzentriert und mehrdimensional. Samtige und strukturierte Tannine schmeicheln dem &#8230; <a href=\"https:\/\/magnusvinum.ch\/de\/shop\/rotweine\/pommard-1er-cru-les-rugiens-aoc-jeroboam\/\" class=\"more-link\">Read More <span class=\"screen-reader-text\">about  Pommard 1er Cru Les Rugiens AOC (JEROBOAM)<\/span><\/a><\/p>\n","protected":false},"featured_media":20090,"template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"product_brand":[],"product_cat":[150],"product_tag":[183],"class_list":["post-11220","product","type-product","status-publish","has-post-thumbnail","product_cat-rotweine","product_tag-2017-de","pa_appellation-pommard-1er-cru-de","pa_bottle-size-3000ml-de","pa_grape-variety-pinot-noir-de","pa_producer-thierry-violot-guillemard-de","pa_region-cote-de-beaune-de","pa_vintage-2017-de","entry","first","outofstock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"wooqr_code":"","_links":{"self":[{"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/product\/11220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/media\/20090"}],"wp:attachment":[{"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/media?parent=11220"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/product_brand?post=11220"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/product_cat?post=11220"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/product_tag?post=11220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}