{"id":11201,"date":"2019-10-29T13:04:07","date_gmt":"2019-10-29T11:35:49","guid":{"rendered":"https:\/\/magnusvinum.ch\/shop\/unkategorisiert\/bourgogne-les-blanches-aoc\/"},"modified":"2026-09-01T21:00:38","modified_gmt":"2026-09-01T19:00:38","slug":"bourgogne-les-blanches-aoc","status":"publish","type":"product","link":"https:\/\/magnusvinum.ch\/de\/shop\/rotweine\/bourgogne-les-blanches-aoc\/","title":{"rendered":"Bourgogne &#8218;Les Blanches&#8216; AOC"},"content":{"rendered":"<p><strong>Degustationsnotiz:<\/strong> Elegante Nase nach frischen Kirschen und Walderdbeeren. Der Geschmack ist frisch, lebhaft und saftig mit leuchtend roten Kirscharomen, feste, kreideartige Tannine, die f\u00fcr Pommard typisch sind, tragen dazu bei, dem Wein L\u00e4nge und Tiefe zu verleihen. Trinken Sie in den n\u00e4chsten zehn Jahren. <strong>Passt gut zu:<\/strong> Passt zu einfach gegrillten Lammkoteletts oder Entecote mit gegrilltem Gem\u00fcse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Degustationsnotiz: Elegante Nase nach frischen Kirschen und Walderdbeeren. Der Geschmack ist frisch, lebhaft und saftig mit leuchtend roten Kirscharomen, feste, kreideartige Tannine, die f\u00fcr Pommard typisch sind, tragen dazu bei, dem Wein L\u00e4nge und Tiefe zu verleihen. Trinken Sie in den n\u00e4chsten zehn Jahren. Passt gut zu: Passt zu einfach gegrillten Lammkoteletts oder Entecote mit &#8230; <a href=\"https:\/\/magnusvinum.ch\/de\/shop\/rotweine\/bourgogne-les-blanches-aoc\/\" class=\"more-link\">Read More <span class=\"screen-reader-text\">about  Bourgogne &#8218;Les Blanches&#8216; AOC<\/span><\/a><\/p>\n","protected":false},"featured_media":20082,"template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"product_brand":[798],"product_cat":[150],"product_tag":[183],"class_list":["post-11201","product","type-product","status-publish","has-post-thumbnail","product_brand-camille-thiriet","product_cat-rotweine","product_tag-2017-de","pa_appellation-bourgogne-de","pa_bottle-size-750ml-de","pa_grape-variety-pinot-noir-de","pa_producer-camille-thiriet-de","pa_region-cote-de-beaune-de","pa_vintage-2017-de","entry","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"wooqr_code":"","_links":{"self":[{"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/product\/11201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/media\/20082"}],"wp:attachment":[{"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/media?parent=11201"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/product_brand?post=11201"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/product_cat?post=11201"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/magnusvinum.ch\/de\/wp-json\/wp\/v2\/product_tag?post=11201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}